{"id":10373,"date":"2026-03-23T20:50:37","date_gmt":"2026-03-23T19:50:37","guid":{"rendered":"https:\/\/couleurs-chakras.com\/?post_type=product&#038;p=10373"},"modified":"2026-03-23T21:13:58","modified_gmt":"2026-03-23T20:13:58","slug":"collier-laura-du-mois-de-mars-aigue-marine","status":"publish","type":"product","link":"https:\/\/couleurs-chakras.com\/index.php\/product\/collier-laura-du-mois-de-mars-aigue-marine\/","title":{"rendered":"Collier L&rsquo;Aura du mois de Mars : Aigue-marine"},"content":{"rendered":"<blockquote><p>&nbsp;<\/p><\/blockquote>\n<p>\u200bD\u00e9couvrez le premier n\u00e9 de notre nouvelle collection \u00ab\u00a0L&rsquo;Aura du Mois\u00a0\u00bb. Un design pur, une pierre unique, une vibration singuli\u00e8re.<\/p>\n<p>L&rsquo;Aigue-marine, pierre de naissance des natifs de mars et protectrice des voyageurs des mers.<\/p>\n<p>\u200b\ud83d\udc8e Les Vertus de votre Aura : L&rsquo;Aigue-Marine<\/p>\n<p>\u200bEn lithoth\u00e9rapie, l&rsquo;Aigue-marine est bien plus qu&rsquo;une couleur, c&rsquo;est une intention :<\/p>\n<p>~\u200bS\u00e9r\u00e9nit\u00e9 : Elle calme les temp\u00eates int\u00e9rieures et r\u00e9duit le stress. Elle est la pierre de la paix et de la relaxation.<\/p>\n<p>~\u200bCommunication : Li\u00e9e au chakra de la gorge, elle aide \u00e0 exprimer ses pens\u00e9es avec clart\u00e9, douceur et conviction.<\/p>\n<p>~\u200b\u00c9panouissement : Elle accompagne les nouveaux d\u00e9parts et favorise l&rsquo;\u00e9coute de soi.<\/p>\n<p>\u200b\u00a0\u00bbPorter l&rsquo;Aigue-marine, c&rsquo;est garder un morceau d&rsquo;oc\u00e9an avec soi, pour ne jamais perdre le nord face aux vagues de la vie.\u00a0\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>\u200b\ud83c\udf81 Pour qui ?<\/p>\n<p>\u200bId\u00e9al pour c\u00e9l\u00e9brer un anniversaire en mars, ou simplement pour celles qui cherchent \u00e0 renforcer leur clart\u00e9 mentale et leur confiance.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u200bD\u00e9couvrez le premier n\u00e9 de notre nouvelle collection \u00ab\u00a0L&rsquo;Aura du Mois\u00a0\u00bb. Un design pur, une pierre unique, une vibration singuli\u00e8re. L&rsquo;Aigue-marine, pierre de naissance des natifs de mars et protectrice des voyageurs des mers. \u200b\ud83d\udc8e Les Vertus de votre Aura : L&rsquo;Aigue-Marine \u200bEn lithoth\u00e9rapie, l&rsquo;Aigue-marine est bien plus qu&rsquo;une couleur, c&rsquo;est une intention :&#8230;<\/p>\n","protected":false},"featured_media":10376,"comment_status":"open","ping_status":"closed","template":"","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[59,65],"product_tag":[],"class_list":["post-10373","product","type-product","status-publish","has-post-thumbnail","product_cat-bijoux","product_cat-pendentif","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple","entry","content-bg","loop-entry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/couleurs-chakras.com\/index.php\/wp-json\/wp\/v2\/product\/10373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/couleurs-chakras.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/couleurs-chakras.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/couleurs-chakras.com\/index.php\/wp-json\/wp\/v2\/comments?post=10373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/couleurs-chakras.com\/index.php\/wp-json\/wp\/v2\/media\/10376"}],"wp:attachment":[{"href":"https:\/\/couleurs-chakras.com\/index.php\/wp-json\/wp\/v2\/media?parent=10373"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/couleurs-chakras.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=10373"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/couleurs-chakras.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=10373"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/couleurs-chakras.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=10373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}